{"id":549,"count":2,"description":"","link":"https:\/\/casvi.es\/en\/tag\/internationality-en\/","name":"Internationality","slug":"internationality-en","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v20.13 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Internationality Archives - Casvi Villaviciosa<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/casvi.es\/en\/tag\/internationality-en\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Internationality Archives\" \/>\n<meta property=\"og:url\" content=\"https:\/\/casvi.es\/en\/tag\/internationality-en\/\" \/>\n<meta property=\"og:site_name\" content=\"Casvi Villaviciosa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Internationality Archives - Casvi Villaviciosa","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/casvi.es\/en\/tag\/internationality-en\/","og_locale":"en_US","og_type":"article","og_title":"Internationality Archives","og_url":"https:\/\/casvi.es\/en\/tag\/internationality-en\/","og_site_name":"Casvi Villaviciosa","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/casvi.es\/en\/tag\/internationality-en\/","url":"https:\/\/casvi.es\/en\/tag\/internationality-en\/","name":"Internationality Archives - Casvi Villaviciosa","isPartOf":{"@id":"https:\/\/casvi.es\/en\/#website"},"breadcrumb":{"@id":"https:\/\/casvi.es\/en\/tag\/internationality-en\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/casvi.es\/en\/tag\/internationality-en\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/casvi.es\/en\/home\/"},{"@type":"ListItem","position":2,"name":"Internationality"}]},{"@type":"WebSite","@id":"https:\/\/casvi.es\/en\/#website","url":"https:\/\/casvi.es\/en\/","name":"Casvi Villaviciosa","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/casvi.es\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/casvi.es\/en\/wp-json\/wp\/v2\/tags\/549","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/casvi.es\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/casvi.es\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/casvi.es\/en\/wp-json\/wp\/v2\/posts?tags=549"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}